{"id":16685,"date":"2026-07-15T11:13:08","date_gmt":"2026-07-15T10:13:08","guid":{"rendered":"https:\/\/neomarca.pt\/pt\/?p=16685"},"modified":"2026-07-15T14:53:02","modified_gmt":"2026-07-15T13:53:02","slug":"algarve2030-candidaturas-abertas-sistemas-de-incentivos-de-base-territorial","status":"publish","type":"post","link":"https:\/\/neomarca.pt\/pt\/noticias\/algarve2030-candidaturas-abertas-sistemas-de-incentivos-de-base-territorial\/","title":{"rendered":"Algarve 2030: candidaturas abertas ao Sistema de Incentivos de Base Territorial"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"103\" height=\"51\" data-src=\"https:\/\/neomarca.pt\/wp-content\/uploads\/2026\/07\/Frame-1-1.png\" alt=\"Algarve 2030\" class=\"wp-image-16690 lazyload\" title=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 103px; --smush-placeholder-aspect-ratio: 103\/51;\"><noscript><img decoding=\"async\" width=\"103\" height=\"51\" src=\"https:\/\/neomarca.pt\/wp-content\/uploads\/2026\/07\/Frame-1-1.png\" alt=\"Algarve 2030\" class=\"wp-image-16690\" title=\"\"><\/noscript><\/figure>\n\n\n<h3>Est\u00e3o abertas as candidaturas ao Sistema de Incentivos de Base Territorial &#8211; Inova\u00e7\u00e3o e moderniza\u00e7\u00e3o para o aumento da produ\u00e7\u00e3o e Cria\u00e7\u00e3o de novas empresas e neg\u00f3cios, no \u00e2mbito do Algarve 2030.<\/h3>\n<p>S\u00e3o suscet\u00edveis de apoio as opera\u00e7\u00f5es que promovam a diversifica\u00e7\u00e3o da base produtiva regional do Algarve:<\/p>\n<p>a) Cria\u00e7\u00e3o de micro e pequenas empresas,<br \/>b) Expans\u00e3o ou moderniza\u00e7\u00e3o das empresas.<\/p>\n<p>Considera-se que as opera\u00e7\u00f5es contribuem para a diversifica\u00e7\u00e3o da base produtiva<strong> quando contribuem para o desenvolvimento de atividades do setor da ind\u00fastria<\/strong>, ou para a <strong>dinamiza\u00e7\u00e3o dos dom\u00ednios da Estrat\u00e9gia Regional do Algarve<\/strong> (Economia do Mar; Recursos End\u00f3genos Terrestres; Ind\u00fastrias Culturais e Criativas; Sa\u00fade; Bem-estar e Longevidade; Sustentabilidade ambiental; Digitaliza\u00e7\u00e3o e TIC).<\/p>\n<p><strong> Benefici\u00e1rios<\/strong><br \/>Podem ser benefici\u00e1rios as micro e pequenas empresas. (Considera-se cria\u00e7\u00e3o uma empresa em fase de arranque, at\u00e9 5 anos ap\u00f3s o in\u00edcio da atividade.)<\/p>\n<p><strong>\u00c1rea Geogr\u00e1fica<\/strong><\/p>\n<p>Algarve<\/p>\n<p><strong>Taxa de cofinanciamento<\/strong><\/p>\n<p>A taxa m\u00e1xima de financiamento das opera\u00e7\u00f5es eleg\u00edveis \u00e9 de 60%, sendo aplicado o seguinte:<\/p>\n<p>Taxa Base:<\/p>\n<ul>\n<li><strong>50 %<\/strong> para os investimentos localizados em <a href=\"https:\/\/neomarca.pt\/pt\/dicas\/portugal-2030-quais-sao-os-territorios-de-baixa-densidade\/\">territ\u00f3rios de baixa densidade<\/a><\/li>\n<li><strong>40 %<\/strong> para os investimentos localizados nos restantes territ\u00f3rios<\/li>\n<li><b>Majora\u00e7\u00e3o: 10 p.p<\/b> \u00abPrioridade Regional\u00bb, para projetos que contribuam para completar as fileiras que se indicam no Anexo D.<\/li>\n<\/ul>\n<p>Os apoios s\u00e3o concedidos ao abrigo do Regulamento (UE) 2023\/2831, da Comiss\u00e3o, de 13 de dezembro de 2023. O montante total dos aux\u00edlios de minimis concedidos por Estado-Membro a uma empresa \u00fanica n\u00e3o pode exceder <strong>300 000 EUR<\/strong> durante um per\u00edodo de tr\u00eas anos.<\/p>\n<p><strong>Per\u00edodo de Candidatura<\/strong><\/p>\n<p>Das 15:00 horas de 30 abril 2025 at\u00e9 \u00e0s 18:00 horas de 18 de dezembro 2025<br \/>Fecho da Fase 1 \u2013 31-07-2025 (18 horas)<br \/>Fecho da Fase 2 \u2013 31-10-2025 (18 horas)<br \/>Fecho da Fase 3 \u2013 18-12-2025 (18 horas)<\/p>\n<p><strong>Condi\u00e7\u00f5es espec\u00edficas dos Avisos:<\/strong><\/p>\n<p><a tabindex=\"0\">Despesas eleg\u00edveis<\/a><\/p>\n<p>Nos termos do artigo 76\u00ba do REITD, consideram-se eleg\u00edveis as seguintes despesas, desde que diretamente relacionadas com o desenvolvimento da opera\u00e7\u00e3o e efetuadas em condi\u00e7\u00f5es de mercado e a entidades fornecedoras com capacidade para o efeito:\u00a0<\/p>\n<p>\u2022 Ativos corp\u00f3reos, incluindo a aquisi\u00e7\u00e3o de m\u00e1quinas e equipamentos, custos diretamente atribu\u00edveis para os colocar na localiza\u00e7\u00e3o e condi\u00e7\u00f5es necess\u00e1rias para os mesmos serem capazes de funcionar, bem como a aquisi\u00e7\u00e3o de equipamentos inform\u00e1ticos, incluindo o software necess\u00e1rio ao seu funcionamento. Estas despesas devem ser amortiz\u00e1veis e inclu\u00eddas nos ativos da empresa;\u00a0<\/p>\n<p>\u2022 Ativos incorp\u00f3reos, incluindo a transfer\u00eancia de tecnologia atrav\u00e9s da aquisi\u00e7\u00e3o de direitos de patentes, nacionais e internacionais, licen\u00e7as, conhecimentos t\u00e9cnicos n\u00e3o protegidos por patente, e software standard ou desenvolvido especificamente para determinado fim. Estas despesas devem ser amortiz\u00e1veis e inclu\u00eddas nos ativos da empresa;<\/p>\n<p>\u2022 Estudos, diagn\u00f3sticos, auditorias, planos de marketing, servi\u00e7os de arquitetura e engenharia relacionados e essenciais \u00e0 implementa\u00e7\u00e3o do projeto de investimento;\u00a0<\/p>\n<p>\u2022 Custos incorridos com a participa\u00e7\u00e3o em feiras e exposi\u00e7\u00f5es no exterior, incluindo o aluguer do espa\u00e7o, a constru\u00e7\u00e3o, o funcionamento do stand; e desloca\u00e7\u00f5es\u00a0<\/p>\n<p>\u2022 Custos de servi\u00e7os de consultoria especializados, prestados por consultores externos, que n\u00e3o constituam uma atividade cont\u00ednua nem peri\u00f3dica, nem estejam relacionados com o normal funcionamento da atividade dos benefici\u00e1rios, incluindo despesas com a interven\u00e7\u00e3o de contabilistas certificados ou de revisores oficiais de contas, na valida\u00e7\u00e3o da despesa dos pedidos de pagamento;\u00a0<\/p>\n<p>\u2022 Custos associados \u00e0 certifica\u00e7\u00e3o de produtos, processos ou servi\u00e7os, custos de conce\u00e7\u00e3o e registo de novas marcas.<\/p>\n<p>\u2022 Constru\u00e7\u00e3o de edif\u00edcios, obras de remodela\u00e7\u00e3o e outras constru\u00e7\u00f5es, desde que devidamente justificados pelo objetivo da opera\u00e7\u00e3o;\u00a0<\/p>\n<p>\u2022 Custos indiretos.<\/p>\n<p><a tabindex=\"0\">Regras de elegibilidade das despesa<\/a><\/p>\n<ol>\n<li>\n<p>O presente Aviso contempla a elegibilidade de despesas com data posterior \u00e0 submiss\u00e3o da candidatura.<\/p>\n<\/li>\n<li>\n<p>Respeitar as demais regras gerais e espec\u00edficas previstas no Regulamento Espec\u00edfico Inova\u00e7\u00e3o e Transi\u00e7\u00e3o Digital.<\/p>\n<\/li>\n<li>\n<p>Os custos eleg\u00edveis diretos apresentados nos pedidos de pagamento do benefici\u00e1rio assentam numa base de custos reais, tendo de ser justificados atrav\u00e9s de faturas pagas ou outros documentos contabil\u00edsticos de valor probat\u00f3rio equivalente.<\/p>\n<\/li>\n<li>\n<p>As despesas apenas s\u00e3o eleg\u00edveis se os bens e servi\u00e7os adquiridos preencherem cumulativamente as seguintes condi\u00e7\u00f5es, conforme disp\u00f5e o n.\u00ba 2 do artigo 76.\u00ba do REITD:<br \/>\u2022 Ser exclusivamente utilizados no estabelecimento do benefici\u00e1rio onde se desenvolve a opera\u00e7\u00e3o;<br \/>\u2022 Ser adquiridos a entidades fornecedoras com capacidade para o efeito;<br \/>\u2022 N\u00e3o ser adquiridos a empresas sedeadas em pa\u00edses, territ\u00f3rios e regi\u00f5es com regimes de tributa\u00e7\u00e3o privilegiada, conforme lista constante da Portaria n.\u00ba 150\/2004, de 13 de fevereiro, na sua reda\u00e7\u00e3o atual, em conformidade com o n.\u00ba 1 do artigo 63.\u00ba-D da Lei Geral Tribut\u00e1ria, aprovada em anexo ao Decreto-Lei n.\u00ba 398\/98, de 17 de dezembro, na sua reda\u00e7\u00e3o atual.<\/p>\n<\/li>\n<li>\n<p>Conforme disposto no n.\u00ba 5 do artigo 20.\u00ba do DL 20-A\/2023 de 22 de mar\u00e7o e no artigo 9.\u00ba do REITD, n\u00e3o s\u00e3o eleg\u00edveis as seguintes despesas:<\/p>\n<\/li>\n<\/ol>\n<ul>\n<li>IVA recuper\u00e1vel, ainda que n\u00e3o tenha sido ou n\u00e3o venha a ser efetivamente recuperado;<\/li>\n<li>Despesas pagas no \u00e2mbito de contratos com intermedi\u00e1rios ou consultores com pagamento em percentagem;<\/li>\n<li>Despesas n\u00e3o suportadas por fatura eletr\u00f3nica ou documento fiscalmente equivalente;<\/li>\n<li>Pagamentos em numer\u00e1rio (exceto at\u00e9 \u20ac250 e quando for o meio mais frequente);<\/li>\n<li>Contratos adicionais que aumentem injustificadamente o custo do projeto;<\/li>\n<li>Multas, coimas, san\u00e7\u00f5es financeiras, juros e despesas de c\u00e2mbio;<\/li>\n<li>Despesas com processos judiciais;<\/li>\n<li>Encargos banc\u00e1rios com empr\u00e9stimos e garantias (salvo a\u00e7\u00f5es relativas a instrumentos financeiros);<\/li>\n<li>Compensa\u00e7\u00f5es por caducidade ou cessa\u00e7\u00e3o de contrato de trabalho, e entregas ao FCT\/FGCT;<\/li>\n<li>Encargos n\u00e3o obrigat\u00f3rios com pessoal afeto \u00e0 opera\u00e7\u00e3o;<\/li>\n<li>Neg\u00f3cios jur\u00eddicos com titulares de cargos sociais, salvo contratos de trabalho pr\u00e9vios \u00e0 candidatura;<\/li>\n<li>Custos normais de funcionamento e investimentos de manuten\u00e7\u00e3o\/substitui\u00e7\u00e3o;<\/li>\n<li>Custos relacionados com atividades peri\u00f3dicas ou cont\u00ednuas (ex.: publicidade corrente, consultoria fiscal de rotina, servi\u00e7os jur\u00eddicos e administrativos);<\/li>\n<li>Investimentos diretos no estrangeiro;<\/li>\n<li>Custos com atividade de exporta\u00e7\u00e3o (quantidades, redes de distribui\u00e7\u00e3o, custos correntes);<\/li>\n<li>Trabalhos realizados pela empresa para ela pr\u00f3pria;<\/li>\n<li>Compra de im\u00f3veis, incluindo terrenos;<\/li>\n<li>Trespasse e direitos de utiliza\u00e7\u00e3o de espa\u00e7os;<\/li>\n<li>Aquisi\u00e7\u00e3o de bens em estado de uso;<\/li>\n<li>Fundo de maneio;<\/li>\n<li>Transa\u00e7\u00f5es entre benefici\u00e1rios da mesma opera\u00e7\u00e3o;<\/li>\n<li>Forma\u00e7\u00e3o para cumprimento de normas legalmente obrigat\u00f3rias.<\/li>\n<\/ul>\n<ol>\n<li>\n<p>Estudos, diagn\u00f3sticos, auditorias, planos de marketing, servi\u00e7os de arquitetura e engenharia relacionados e essenciais \u00e0 implementa\u00e7\u00e3o do projeto s\u00e3o eleg\u00edveis at\u00e9 15% do investimento total da candidatura.<\/p>\n<\/li>\n<li>\n<p>Os custos indiretos dos benefici\u00e1rios s\u00e3o eleg\u00edveis atrav\u00e9s da aplica\u00e7\u00e3o da Op\u00e7\u00e3o de Custos Simplificados (OCS), correspondendo a uma taxa fixa de 7% sobre o total dos custos diretos eleg\u00edveis.<\/p>\n<\/li>\n<li>\n<p>Os custos com a interven\u00e7\u00e3o de contabilistas certificados ou revisores oficiais de contas, na valida\u00e7\u00e3o da despesa dos pedidos de pagamento, n\u00e3o podem exceder 5.000 euros.<\/p>\n<\/li>\n<\/ol>\n<p><a tabindex=\"0\">Crit\u00e9rios de elegibilidade dos benefici\u00e1rios<\/a><\/p>\n<p>Para serem suscet\u00edveis de apoio, as opera\u00e7\u00f5es devem cumprir os requisitos de elegibilidade previstos nos artigos 14.\u00ba e 19.\u00ba do Decreto-Lei n.\u00ba 20-A\/2023, de 22 de mar\u00e7o, e nos artigos 6.\u00ba, 7.\u00ba, 72.\u00ba e 73.\u00ba do REITD, na reda\u00e7\u00e3o atual, e satisfazer as seguintes condi\u00e7\u00f5es espec\u00edficas de acesso:\u00a0<\/p>\n<ol>\n<li>\n<p>Contribuir para as finalidades e objetivos do presente Aviso;<\/p>\n<\/li>\n<li>\n<p>Demonstrar dispor de fontes de financiamento para assegurar a realiza\u00e7\u00e3o da opera\u00e7\u00e3o;<\/p>\n<\/li>\n<li>\n<p>Apresentar uma autoavalia\u00e7\u00e3o do alinhamento dos investimentos a realizar com o Princ\u00edpio \u00abN\u00e3o Prejudicar Significativamente\u00bb, conforme definido no n.\u00ba 3 do artigo 77.\u00ba do REITD, na reda\u00e7\u00e3o atual;<\/p>\n<\/li>\n<li>\n<p>Apresentar um investimento eleg\u00edvel igual ou superior a 25.000,00 \u20ac (vinte e cinco mil euros);<\/p>\n<\/li>\n<li>\n<p>Ter, \u00e0 data da candidatura, pelo menos, um posto de trabalho remunerado, em ETI, afeto ao estabelecimento da empresa na NUT II Algarve, a evidenciar conforme documentos a apresentar no Anexo A-1;<\/p>\n<\/li>\n<li>\n<p>Opera\u00e7\u00f5es que contribuam para a RIS3 devem apresentar uma justifica\u00e7\u00e3o que demonstre de forma clara que os resultados a alcan\u00e7ar, considerados no indicador de realiza\u00e7\u00e3o RP057, se enquadram no \u00e2mbito da dinamiza\u00e7\u00e3o das a\u00e7\u00f5es transformativas dos dom\u00ednios da EREI Algarve (Economia do Mar; Recursos End\u00f3genos Terrestres; Ind\u00fastrias Culturais e Criativas; Sa\u00fade, Bem-Estar e Longevidade; Sustentabilidade Ambiental; Digitaliza\u00e7\u00e3o e TIC);<\/p>\n<\/li>\n<li>\n<p>As atividades devem enquadrar-se no Regulamento (UE) 2023\/2831, da Comiss\u00e3o, de 13 de dezembro de 2023 (Aux\u00edlios de minimis).<\/p>\n<\/li>\n<\/ol>\n<h5>Pretende obter mais informa\u00e7\u00f5es?<\/h5>\n<p>Agende uma reuni\u00e3o com a nossa equipa de especialistas.<\/p>\n<p><a href=\"mailto:info@neomarca.eu\"><br \/>Agendar Reuni\u00e3o<br \/><\/a><\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas as candidaturas ao Sistema de Incentivos de Base Territorial &#8211; Inova\u00e7\u00e3o e moderniza\u00e7\u00e3o para o aumento da produ\u00e7\u00e3o e Cria\u00e7\u00e3o de novas empresas e neg\u00f3cios, no \u00e2mbito do Algarve 2030. S\u00e3o suscet\u00edveis de apoio as opera\u00e7\u00f5es que promovam a diversifica\u00e7\u00e3o da base produtiva regional do Algarve: a) Cria\u00e7\u00e3o de micro e pequenas empresas,b)&hellip;<\/p>\n","protected":false},"author":20,"featured_media":16529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[363,238],"tags":[419,112,282,122,346],"class_list":["post-16685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-candidaturas-abertas","category-noticias","tag-algarve-2030","tag-apoio-investimento","tag-empresas","tag-fundos-comunitarios","tag-portugal-2030","category-363","category-238","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/posts\/16685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/comments?post=16685"}],"version-history":[{"count":3,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/posts\/16685\/revisions"}],"predecessor-version":[{"id":16693,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/posts\/16685\/revisions\/16693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/media\/16529"}],"wp:attachment":[{"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/media?parent=16685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/categories?post=16685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neomarca.pt\/pt\/wp-json\/wp\/v2\/tags?post=16685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}